{"id":2350,"date":"2024-07-08T13:35:13","date_gmt":"2024-07-08T16:35:13","guid":{"rendered":"https:\/\/www.linti.unlp.edu.ar\/?p=2350"},"modified":"2024-12-18T10:12:53","modified_gmt":"2024-12-18T13:12:53","slug":"53-jornadas-argentinas-de-informatica","status":"publish","type":"post","link":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/","title":{"rendered":"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Del 12 al 16 de agosto de 2024 se llevar\u00e1n a cabo las 53 Jornadas Argentinas de Inform\u00e1tica (JAIIO 53) en la Universidad Nacional del Sur ubicada en la ciudad de Bah\u00eda Blanca, provincia de Buenos Aires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las Jornadas Argentinas de Inform\u00e1tica (JAIIO) se realizan desde 1961, organizadas por la Sociedad Argentina de Inform\u00e1tica (SADIO). Las JAIIOs re\u00fanen investigadores, estudiantes y profesionales provenientes de la academia, la industria y el gobierno, tanto argentinos como extranjeros, con el objetivo de extender el conocimiento de la disciplina inform\u00e1tica, estimular los v\u00ednculos y promover la ense\u00f1anza, la investigaci\u00f3n y las aplicaciones en esta disciplina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las JAIIOs se organizan como un conjunto de simposios, de uno o dos d\u00edas de duraci\u00f3n, cada uno dedicado a un tema espec\u00edfico. En esta oportunidad los chairs generales ser\u00e1n <strong>Rodrigo Santos<\/strong> de la Universidad Nacional del Sur y <strong>Claudia Pons<\/strong> de la Universidad Nacional de La Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la docente e investigadora del LINTI<strong> Claudia Queiruga <\/strong>estar\u00e1 a cargo del Simposio Argentino de Ense\u00f1anza de la Inform\u00e1tica (SAEI). Se trata de un espacio reflexivo y anal\u00edtico en torno a los diversos marcos te\u00f3ricos metodol\u00f3gicos vinculados a la ense\u00f1anza de la inform\u00e1tica y sus ciencias afines y que propicia integrar experiencias pedag\u00f3gicas innovadoras en diversos contextos tanto formales como no formales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Simposios<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/jaiio53.clei.org\/asaid\/\" target=\"_blank\" rel=\"noreferrer noopener\">ASAID \u2013 Simposio Argentino de Inteligencia Artificial y Ciencia de Datos<\/a><br>Axel Soto \u2013 Universidad Nacional del Sur<br>Maximiliano Bud\u00e1n \u2013 Universidad Nacional del Sur \/ Universidad Nacional de Santiago del Estero \/ CONICET<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/asse\/\" target=\"_blank\" rel=\"noreferrer noopener\">ASSE \u2013 Simposio Argentino de Ingenier\u00eda de Software<\/a><br>Juli\u00e1n Grigera \u2013 UNLP<br>Mar\u00eda Julia Blas \u2013 INGAR (Conicet \u2013 UTN)<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/cai\/\" target=\"_blank\" rel=\"noreferrer noopener\">CAI \u2013 Congreso Argentino de AgroInform\u00e1tica<\/a><br>Flavio Capraro \u2013 Instituto de Autom\u00e1tica (UNSJ-CONICET)<br>Mat\u00edas Micheletto \u2013 CIT San Jorge \u2013 CONICET<br>Juan Pablo Damico \u2013 INTA<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/cais\/\" target=\"_blank\" rel=\"noreferrer noopener\">CAIS \u2013 Congreso Argentino de Inform\u00e1tica y Salud<\/a><br>Mart\u00edn D\u00edaz \u2013 Ministerio de Salud de la Naci\u00f3n<br>Alejandro Viegas Palermo \u2013 Armada Argentina<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/est\/\" target=\"_blank\" rel=\"noreferrer noopener\">EST \u2013 Concurso de Trabajos Estudiantiles<\/a><br>Ricardo Cayssials \u2013 FRBB\/UTN \u2013 UNS<br>Fernando Asteasuain \u2013 DCIC-UNS<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/ietf-day\/\" target=\"_blank\" rel=\"noreferrer noopener\">IETF Day \u2013 Taller del Grupo de Trabajo de Ingenier\u00eda de Internet\/Argentina<\/a><br>Gustavo Mercado \u2013 UTN FRM<br>Marcela Orbiscay \u2013 IANIGLA \u2013 CONICET \u2013 Mendoza<br>Ignacio Alvarez-Hamelin \u2013 FIUBA<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/jui\/\" target=\"_blank\" rel=\"noreferrer noopener\">JUI \u2013 Jornadas de Vinculaci\u00f3n Universidad \u2013 Industria<\/a><br>Ricardo Medel \u2013 Fundaci\u00f3n Sadosky<br>Federico Balaguer \u2013 UNLP<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/sacs\/\" target=\"_blank\" rel=\"noreferrer noopener\">SACS \u2013 Simposio Argentino de Ciberseguridad y Ciberdefensa<\/a><br>Gladys Mart\u00ednez \u2013 Fuerza A\u00e9rea<br>Mar\u00eda Luciana Rold\u00e1n \u2013 INGAR \u2013 (Conicet\/UTN)<br>Rub\u00e9n Dar\u00edo Aybar \u2013 AFIP \u2013 ICFFAA \u2013 UBA \u2013 UNSO \u2013 UCASAL \u2013 FIE<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/saei\/\">SAEI \u2013 Simposio Argentino de Educaci\u00f3n en Inform\u00e1tica<\/a><br><a href=\"https:\/\/www.extension.info.unlp.edu.ar\/secretaria-de-extension-de-la-facultad-de-informatica\/\" target=\"_blank\" rel=\"noreferrer noopener\">Claudia Queiruga \u2013 LINTI \u2013 UNLP<\/a><br>Natalia Colussi \u2013 UNR<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/saei\/\" target=\"_blank\" rel=\"noreferrer noopener\">SAHTI \u2013 Simposio Argentino de Historia, Tecnolog\u00edas e Inform\u00e1tica \/ SHIALC \u2013 Simposio de Historia de la Inform\u00e1tica en Am\u00e9rica Latina y Caribe<\/a><br>Karina Bianculli \u2013 CEHIS, UNMdP<br>Bruno Massare \u2013 UNSaM<br>Nicol\u00e1s Wolowick \u2013 FaMAF \u2013 UNC<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/saic\/\" target=\"_blank\" rel=\"noreferrer noopener\">SAIC \u2013 Simposio Argentino en Ingenier\u00eda en Computaci\u00f3n<\/a><br>Jos\u00e9 Moyano \u2013 Universidad Nacional del Sur<br>Karina Cenci \u2013 Universidad Nacional del Sur<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/saiv\/\" target=\"_blank\" rel=\"noreferrer noopener\">SAIV \u2013 Simposio Argentino de Im\u00e1genes y Visi\u00f3n<\/a><br>Mar\u00eda Elena Buemi \u2013 DC-FCEyN UBA\/ICC-Conicet\/UNSAM<br>Daniel Acevedo \u2013 DC-FCEyN UBA\/ICC-Conicet<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/sids\/\" target=\"_blank\" rel=\"noreferrer noopener\">SIDS \u2013 Simposio Argentino de Informatica, Derecho y Sociedad<\/a><br>Ariel Vercelli \u2013 CONICET \/ IESCT-UNQ<br>Florencia Gianfelici \u2013 UNL<br>Corina Iuale \u2013 UNS<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/sie\/\" target=\"_blank\" rel=\"noreferrer noopener\">SIE \u2013 Simposio de Inform\u00e1tica en el Estado<\/a><br>Sandra D\u00b4Agostino \u2013 UNLP<br>Marcelo Daniel Petroff \u2013 UNRN<br>Elsa Est\u00e9vez \u2013 UNS<\/li>\n\n\n\n<li><a href=\"https:\/\/jaiio53.clei.org\/siiio\/\" target=\"_blank\" rel=\"noreferrer noopener\">SIIIO \u2013 Simposio Argentino de Inform\u00e1tica Industrial e Investigaci\u00f3n Operativa<\/a><br>Mariano Frutos \u2013 UNS<br>Pablo Rey \u2013 Univ. Tecnol\u00f3gica Metropolitana (Chile)<br>Mariana Coccola \u2013 CONICET \/ UTN-FRCU<br>Diego Rossit \u2013 UNS<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Fechas importantes de la 53 Jornadas Argentinas de Inform\u00e1tica<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>24 de marzo: cierre de recepci\u00f3n de res\u00famenes<\/li>\n\n\n\n<li>31 de marzo: cierre de recepci\u00f3n de contribuciones<\/li>\n\n\n\n<li>27 de mayo: notificaci\u00f3n de trabajos aceptados<\/li>\n\n\n\n<li>17 de junio: l\u00edmite de recepci\u00f3n de trabajos &#8220;Camera Ready&#8221;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">50\u00aa Conferencia Latinoamericana de Inform\u00e1tica (50 CLEI)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o las jornadas se llevar\u00e1n a cabo en conjunto con la 50\u00aa Conferencia Latinoamericana de Inform\u00e1tica (50 CLEI). <br>La CLEI es un evento anual organizado por el Centro Latinoamericano de Estudios de Inform\u00e1tica y, ocurre desde 1974, de modo itinerante por los pa\u00edses de Am\u00e9rica Latina. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata del espacio latinoamericano m\u00e1s importante de intercambio de ideas, experiencias y resultados de investigaci\u00f3n entre investigadores, profesionales, docentes y estudiantes de Ciencias de la Computaci\u00f3n e Inform\u00e1tica, as\u00ed como sus aplicaciones tecnol\u00f3gicas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este evento tiene como objetivo el intercambio de ideas, experiencias y resultados de investigaci\u00f3n en las \u00e1reas de inter\u00e9s de la comunidad por medio de conferencias, talleres, tutoriales y paneles. Por este motivo, invita a presentar trabajos que reporten resultados de naturaleza te\u00f3rica y\/o pr\u00e1ctica que avancen el estado del arte o presenten aplicaciones o casos relevantes en las \u00e1reas de inter\u00e9s de los simposios y eventos asociados. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La CLEI, este a\u00f1o,  estar\u00e1 compuesta por 5 tracks, 6 eventos asociados y 2 eventos paralelos. Asimismo, los chair generales ser\u00e1n  el Dr. Marcelo Falappa de la UNS, Argentina y el Dr. Carlos Luna de UDELAR, Uruguay.  Por otra parte los chairs acad\u00e9micos ser\u00e1n Dr. Carlos Ches\u00f1evar de la UNS, Argentina y el Dr. Jos\u00e9 Miguel Rojas de U. Sheffield, UK.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fechas importantes<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>5 de abril: fecha l\u00edmite para el env\u00edo de trabajos general<\/li>\n\n\n\n<li>26 de abril: postulaci\u00f3n cursos ELI tem\u00e1ticos<\/li>\n\n\n\n<li>10 de mayo: concursos de tesis<\/li>\n\n\n\n<li>14 de junio: notificaci\u00f3n a autores y propuestas cursos ELI<\/li>\n\n\n\n<li>19 de julio: versi\u00f3n final<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/jaiio53.clei.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1s informaci\u00f3n<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Del 12 al 16 de agosto de 2024 se llevar\u00e1n a cabo las 53 Jornadas Argentinas de Inform\u00e1tica (JAIIO 53) en la Universidad Nacional del Sur ubicada en la ciudad de Bah\u00eda Blanca, provincia de Buenos Aires. Las Jornadas Argentinas de Inform\u00e1tica (JAIIO) se realizan desde 1961, organizadas por la Sociedad Argentina de Inform\u00e1tica (SADIO). Las JAIIOs re\u00fanen investigadores, estudiantes y profesionales provenientes de la academia, la industria y el gobierno, tanto argentinos como extranjeros, con el objetivo de extender el conocimiento de la disciplina inform\u00e1tica, estimular los v\u00ednculos y promover la ense\u00f1anza, la investigaci\u00f3n y las aplicaciones en esta disciplina. Las JAIIOs se organizan como un conjunto de simposios, de uno o dos d\u00edas de duraci\u00f3n, cada uno dedicado a un tema espec\u00edfico. En esta oportunidad los chairs generales ser\u00e1n Rodrigo Santos de la Universidad Nacional del Sur y Claudia Pons de la Universidad Nacional de La Plata. Asimismo, la docente e investigadora del LINTI Claudia Queiruga estar\u00e1 a cargo del Simposio Argentino de Ense\u00f1anza de la Inform\u00e1tica (SAEI). Se trata de un espacio reflexivo y anal\u00edtico en torno a los diversos marcos te\u00f3ricos metodol\u00f3gicos vinculados a la ense\u00f1anza de la inform\u00e1tica y sus ciencias afines y que propicia integrar experiencias pedag\u00f3gicas innovadoras en diversos contextos tanto formales como no formales. Simposios Fechas importantes de la 53 Jornadas Argentinas de Inform\u00e1tica 50\u00aa Conferencia Latinoamericana de Inform\u00e1tica (50 CLEI) Este a\u00f1o las jornadas se llevar\u00e1n a cabo en conjunto con la 50\u00aa Conferencia Latinoamericana de Inform\u00e1tica (50 CLEI). La CLEI es un evento anual organizado por el Centro Latinoamericano de Estudios de Inform\u00e1tica y, ocurre desde 1974, de modo itinerante por los pa\u00edses de Am\u00e9rica Latina. Se trata del espacio latinoamericano m\u00e1s importante de intercambio de ideas, experiencias y resultados de investigaci\u00f3n entre investigadores, profesionales, docentes y estudiantes de Ciencias de la Computaci\u00f3n e Inform\u00e1tica, as\u00ed como sus aplicaciones tecnol\u00f3gicas. Este evento tiene como objetivo el intercambio de ideas, experiencias y resultados de investigaci\u00f3n en las \u00e1reas de inter\u00e9s de la comunidad por medio de conferencias, talleres, tutoriales y paneles. Por este motivo, invita a presentar trabajos que reporten resultados de naturaleza te\u00f3rica y\/o pr\u00e1ctica que avancen el estado del arte o presenten aplicaciones o casos relevantes en las \u00e1reas de inter\u00e9s de los simposios y eventos asociados. La CLEI, este a\u00f1o, estar\u00e1 compuesta por 5 tracks, 6 eventos asociados y 2 eventos paralelos. Asimismo, los chair generales ser\u00e1n el Dr. Marcelo Falappa de la UNS, Argentina y el Dr. Carlos Luna de UDELAR, Uruguay. Por otra parte los chairs acad\u00e9micos ser\u00e1n Dr. Carlos Ches\u00f1evar de la UNS, Argentina y el Dr. Jos\u00e9 Miguel Rojas de U. Sheffield, UK. Fechas importantes M\u00e1s informaci\u00f3n<\/p>\n","protected":false},"author":6,"featured_media":2351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-2350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investigacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>53 Jornadas Argentinas de Inform\u00e1tica<\/title>\n<meta name=\"description\" content=\"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO): se realizar\u00e1n del 12 al 16 de agosto de 2024 en la Universidad Nacional del Sur, Bah\u00eda Blanca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"53 Jornadas Argentinas de Inform\u00e1tica\" \/>\n<meta property=\"og:description\" content=\"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO): se realizar\u00e1n del 12 al 16 de agosto de 2024 en la Universidad Nacional del Sur, Bah\u00eda Blanca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Laboratorio de Investigaci\u00f3n en Nuevas Tecnolog\u00edas Inform\u00e1ticas\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T16:35:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-18T13:12:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.linti.unlp.edu.ar\/wp-content\/uploads\/2024\/07\/JAIIO-53.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dialogo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dialogo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/\"},\"author\":{\"name\":\"dialogo\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#\\\/schema\\\/person\\\/e0089983e0c5e6a290bb4cfbce05631d\"},\"headline\":\"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO)\",\"datePublished\":\"2024-07-08T16:35:13+00:00\",\"dateModified\":\"2024-12-18T13:12:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/\"},\"wordCount\":881,\"publisher\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/JAIIO-53.jpeg\",\"articleSection\":[\"Investigaci\u00f3n\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/\",\"url\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/\",\"name\":\"53 Jornadas Argentinas de Inform\u00e1tica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/JAIIO-53.jpeg\",\"datePublished\":\"2024-07-08T16:35:13+00:00\",\"dateModified\":\"2024-12-18T13:12:53+00:00\",\"description\":\"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO): se realizar\u00e1n del 12 al 16 de agosto de 2024 en la Universidad Nacional del Sur, Bah\u00eda Blanca.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/JAIIO-53.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/JAIIO-53.jpeg\",\"width\":800,\"height\":423},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/2024\\\/07\\\/08\\\/53-jornadas-argentinas-de-informatica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#website\",\"url\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/\",\"name\":\"Laboratorio de Investigaci\u00f3n en Nuevas Tecnolog\u00edas Inform\u00e1ticas\",\"description\":\"Laboratorio de investigaci\u00f3n tecnol\u00f3gica de la Facultad de Inform\u00e1tica de la Universidad Nacional de La Plata\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#organization\"},\"alternateName\":\"LINTI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#organization\",\"name\":\"Laboratorio de Investigaci\u00f3n en Nuevas Tecnolog\u00edas Inform\u00e1ticas\",\"alternateName\":\"LINTI\",\"url\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/fachada-LINTI.jpg\",\"contentUrl\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/fachada-LINTI.jpg\",\"width\":589,\"height\":411,\"caption\":\"Laboratorio de Investigaci\u00f3n en Nuevas Tecnolog\u00edas Inform\u00e1ticas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/#\\\/schema\\\/person\\\/e0089983e0c5e6a290bb4cfbce05631d\",\"name\":\"dialogo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5491754f71b81730abb27a88b1eb511f2556aa339d1c308e3d3f1db0c11ecede?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5491754f71b81730abb27a88b1eb511f2556aa339d1c308e3d3f1db0c11ecede?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5491754f71b81730abb27a88b1eb511f2556aa339d1c308e3d3f1db0c11ecede?s=96&d=mm&r=g\",\"caption\":\"dialogo\"},\"url\":\"https:\\\/\\\/www.linti.unlp.edu.ar\\\/index.php\\\/author\\\/dialogo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"53 Jornadas Argentinas de Inform\u00e1tica","description":"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO): se realizar\u00e1n del 12 al 16 de agosto de 2024 en la Universidad Nacional del Sur, Bah\u00eda Blanca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/","og_locale":"es_ES","og_type":"article","og_title":"53 Jornadas Argentinas de Inform\u00e1tica","og_description":"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO): se realizar\u00e1n del 12 al 16 de agosto de 2024 en la Universidad Nacional del Sur, Bah\u00eda Blanca.","og_url":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/","og_site_name":"Laboratorio de Investigaci\u00f3n en Nuevas Tecnolog\u00edas Inform\u00e1ticas","article_published_time":"2024-07-08T16:35:13+00:00","article_modified_time":"2024-12-18T13:12:53+00:00","og_image":[{"width":800,"height":423,"url":"https:\/\/www.linti.unlp.edu.ar\/wp-content\/uploads\/2024\/07\/JAIIO-53.jpeg","type":"image\/jpeg"}],"author":"dialogo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"dialogo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/#article","isPartOf":{"@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/"},"author":{"name":"dialogo","@id":"https:\/\/www.linti.unlp.edu.ar\/#\/schema\/person\/e0089983e0c5e6a290bb4cfbce05631d"},"headline":"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO)","datePublished":"2024-07-08T16:35:13+00:00","dateModified":"2024-12-18T13:12:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/"},"wordCount":881,"publisher":{"@id":"https:\/\/www.linti.unlp.edu.ar\/#organization"},"image":{"@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.linti.unlp.edu.ar\/wp-content\/uploads\/2024\/07\/JAIIO-53.jpeg","articleSection":["Investigaci\u00f3n"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/","url":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/","name":"53 Jornadas Argentinas de Inform\u00e1tica","isPartOf":{"@id":"https:\/\/www.linti.unlp.edu.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/#primaryimage"},"image":{"@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.linti.unlp.edu.ar\/wp-content\/uploads\/2024\/07\/JAIIO-53.jpeg","datePublished":"2024-07-08T16:35:13+00:00","dateModified":"2024-12-18T13:12:53+00:00","description":"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO): se realizar\u00e1n del 12 al 16 de agosto de 2024 en la Universidad Nacional del Sur, Bah\u00eda Blanca.","breadcrumb":{"@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/#primaryimage","url":"https:\/\/www.linti.unlp.edu.ar\/wp-content\/uploads\/2024\/07\/JAIIO-53.jpeg","contentUrl":"https:\/\/www.linti.unlp.edu.ar\/wp-content\/uploads\/2024\/07\/JAIIO-53.jpeg","width":800,"height":423},{"@type":"BreadcrumbList","@id":"https:\/\/www.linti.unlp.edu.ar\/index.php\/2024\/07\/08\/53-jornadas-argentinas-de-informatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.linti.unlp.edu.ar\/"},{"@type":"ListItem","position":2,"name":"53 Jornadas Argentinas de Inform\u00e1tica (JAIIO)"}]},{"@type":"WebSite","@id":"https:\/\/www.linti.unlp.edu.ar\/#website","url":"https:\/\/www.linti.unlp.edu.ar\/","name":"Laboratorio de Investigaci\u00f3n en Nuevas Tecnolog\u00edas Inform\u00e1ticas","description":"Laboratorio de investigaci\u00f3n tecnol\u00f3gica de la Facultad de Inform\u00e1tica de la Universidad Nacional de La Plata","publisher":{"@id":"https:\/\/www.linti.unlp.edu.ar\/#organization"},"alternateName":"LINTI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.linti.unlp.edu.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/www.linti.unlp.edu.ar\/#organization","name":"Laboratorio de Investigaci\u00f3n en Nuevas Tecnolog\u00edas Inform\u00e1ticas","alternateName":"LINTI","url":"https:\/\/www.linti.unlp.edu.ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.linti.unlp.edu.ar\/#\/schema\/logo\/image\/","url":"https:\/\/www.linti.unlp.edu.ar\/wp-content\/uploads\/2022\/05\/fachada-LINTI.jpg","contentUrl":"https:\/\/www.linti.unlp.edu.ar\/wp-content\/uploads\/2022\/05\/fachada-LINTI.jpg","width":589,"height":411,"caption":"Laboratorio de Investigaci\u00f3n en Nuevas Tecnolog\u00edas Inform\u00e1ticas"},"image":{"@id":"https:\/\/www.linti.unlp.edu.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.linti.unlp.edu.ar\/#\/schema\/person\/e0089983e0c5e6a290bb4cfbce05631d","name":"dialogo","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/5491754f71b81730abb27a88b1eb511f2556aa339d1c308e3d3f1db0c11ecede?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5491754f71b81730abb27a88b1eb511f2556aa339d1c308e3d3f1db0c11ecede?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5491754f71b81730abb27a88b1eb511f2556aa339d1c308e3d3f1db0c11ecede?s=96&d=mm&r=g","caption":"dialogo"},"url":"https:\/\/www.linti.unlp.edu.ar\/index.php\/author\/dialogo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/2350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2350"}],"version-history":[{"count":1,"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/2350\/revisions"}],"predecessor-version":[{"id":2352,"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/2350\/revisions\/2352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/2351"}],"wp:attachment":[{"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.linti.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}